{"id":92,"count":3,"description":"","link":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/","name":"Rossi","slug":"rossi-de","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rossi Archivi - Colli Vai Bo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collivaibo.it\/de\/category\/rossi-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rossi Archivi - Colli Vai Bo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collivaibo.it\/de\/category\/rossi-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Colli Vai Bo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/de\\\/category\\\/rossi-de\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/de\\\/category\\\/rossi-de\\\/\",\"name\":\"Rossi Archivi - Colli Vai Bo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/de\\\/category\\\/rossi-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/de\\\/category\\\/rossi-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/collivaibo.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rossi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"name\":\"Colli Vai Bo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collivaibo.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rossi Archivi - Colli Vai Bo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/","og_locale":"de_DE","og_type":"article","og_title":"Rossi Archivi - Colli Vai Bo","og_url":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/","og_site_name":"Colli Vai Bo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/","url":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/","name":"Rossi Archivi - Colli Vai Bo","isPartOf":{"@id":"https:\/\/collivaibo.it\/#website"},"breadcrumb":{"@id":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/collivaibo.it\/de\/category\/rossi-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/collivaibo.it\/de\/"},{"@type":"ListItem","position":2,"name":"Rossi"}]},{"@type":"WebSite","@id":"https:\/\/collivaibo.it\/#website","url":"https:\/\/collivaibo.it\/","name":"Colli Vai Bo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collivaibo.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/collivaibo.it\/de\/wp-json\/wp\/v2\/categories\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collivaibo.it\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/collivaibo.it\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/collivaibo.it\/de\/wp-json\/wp\/v2\/posts?categories=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}