

{"id":7596,"date":"2023-04-12T16:52:14","date_gmt":"2023-04-12T15:52:14","guid":{"rendered":"https:\/\/collivaibo.it\/present-at-prowein-2020\/"},"modified":"2023-10-18T14:06:55","modified_gmt":"2023-10-18T13:06:55","slug":"present-at-prowein-2020","status":"publish","type":"post","link":"https:\/\/collivaibo.it\/en\/present-at-prowein-2020\/","title":{"rendered":"PRESENT AT PROWEIN 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7596\" class=\"elementor elementor-7596 elementor-7168\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f49906 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f49906\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-933a306\" data-id=\"933a306\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dbab60 elementor-widget elementor-widget-image\" data-id=\"3dbab60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"637\" height=\"637\" src=\"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2.png\" class=\"attachment-large size-large wp-image-7421\" alt=\"\" srcset=\"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2.png 637w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-300x300.png 300w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-150x150.png 150w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-630x630.png 630w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-600x600.png 600w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-100x100.png 100w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-50x50.png 50w, https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/prowein-2-460x460.png 460w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed40f97 elementor-widget elementor-widget-heading\" data-id=\"ed40f97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">PRESENT AT PROWEIN 2020<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c06327 elementor-widget elementor-widget-text-editor\" data-id=\"1c06327\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<article id=\"post-10833\" class=\"post-10833 post type-post status-publish format-standard has-post-thumbnail hentry category-eventi\">\n<div class=\"eltdf-post-content\">\n<div class=\"eltdf-post-text\">\n<article id=\"post-10858\" class=\"post-10858 post type-post status-publish format-standard has-post-thumbnail hentry category-eventi\">\n<div class=\"eltdf-post-content\">\n<div class=\"eltdf-post-text\">\n<p><strong>March 15-17, 2020<\/strong><br \/><strong>D\u00fcsseldorf, Germany<\/strong><\/p>\n<p>COME VISIT US<\/p>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"eltdf-blog-single-navigation\"> <\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"eltdf-blog-single-navigation\"> <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PRESENT AT PROWEIN 2020 March 15-17, 2020D\u00fcsseldorf, Germany COME VISIT US<\/p>\n","protected":false},"author":218,"featured_media":9495,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","footnotes":""},"categories":[80],"tags":[],"class_list":["post-7596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRESENT AT PROWEIN 2020 - Colli Vai Bo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRESENT AT PROWEIN 2020 - Colli Vai Bo\" \/>\n<meta property=\"og:description\" content=\"PRESENT AT PROWEIN 2020 March 15-17, 2020D\u00fcsseldorf, Germany COME VISIT US\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Colli Vai Bo\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-12T15:52:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-18T13:06:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Madl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Madl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/\"},\"author\":{\"name\":\"Madl\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/person\\\/850b4c503bc845b7601f6b66d8fc754c\"},\"headline\":\"PRESENT AT PROWEIN 2020\",\"datePublished\":\"2023-04-12T15:52:14+00:00\",\"dateModified\":\"2023-10-18T13:06:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/\",\"name\":\"PRESENT AT PROWEIN 2020 - Colli Vai Bo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"datePublished\":\"2023-04-12T15:52:14+00:00\",\"dateModified\":\"2023-10-18T13:06:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"width\":649,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/presenti-a-prowein-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESENT AT PROWEIN 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"name\":\"Colli Vai Bo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collivaibo.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\",\"name\":\"Colli Vai Bo\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-Logo-trasparente-1.png\",\"contentUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-Logo-trasparente-1.png\",\"width\":775,\"height\":367,\"caption\":\"Colli Vai Bo\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/person\\\/850b4c503bc845b7601f6b66d8fc754c\",\"name\":\"Madl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g\",\"caption\":\"Madl\"},\"sameAs\":[\"https:\\\/\\\/madl-image.it\\\/\"],\"url\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/author\\\/wp-madl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRESENT AT PROWEIN 2020 - Colli Vai Bo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/","og_locale":"en_US","og_type":"article","og_title":"PRESENT AT PROWEIN 2020 - Colli Vai Bo","og_description":"PRESENT AT PROWEIN 2020 March 15-17, 2020D\u00fcsseldorf, Germany COME VISIT US","og_url":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/","og_site_name":"Colli Vai Bo","article_published_time":"2023-04-12T15:52:14+00:00","article_modified_time":"2023-10-18T13:06:55+00:00","og_image":[{"width":649,"height":350,"url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/3.jpg","type":"image\/jpeg"}],"author":"Madl","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Madl"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#article","isPartOf":{"@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/"},"author":{"name":"Madl","@id":"https:\/\/collivaibo.it\/#\/schema\/person\/850b4c503bc845b7601f6b66d8fc754c"},"headline":"PRESENT AT PROWEIN 2020","datePublished":"2023-04-12T15:52:14+00:00","dateModified":"2023-10-18T13:06:55+00:00","mainEntityOfPage":{"@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/"},"wordCount":14,"publisher":{"@id":"https:\/\/collivaibo.it\/#organization"},"image":{"@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/3.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/","url":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/","name":"PRESENT AT PROWEIN 2020 - Colli Vai Bo","isPartOf":{"@id":"https:\/\/collivaibo.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#primaryimage"},"image":{"@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/3.jpg","datePublished":"2023-04-12T15:52:14+00:00","dateModified":"2023-10-18T13:06:55+00:00","breadcrumb":{"@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/collivaibo.it\/presenti-a-prowein-2020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#primaryimage","url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/3.jpg","contentUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2023\/04\/3.jpg","width":649,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/collivaibo.it\/presenti-a-prowein-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/collivaibo.it\/en\/"},{"@type":"ListItem","position":2,"name":"PRESENT AT PROWEIN 2020"}]},{"@type":"WebSite","@id":"https:\/\/collivaibo.it\/#website","url":"https:\/\/collivaibo.it\/","name":"Colli Vai Bo","description":"","publisher":{"@id":"https:\/\/collivaibo.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collivaibo.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/collivaibo.it\/#organization","name":"Colli Vai Bo","url":"https:\/\/collivaibo.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collivaibo.it\/#\/schema\/logo\/image\/","url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2021\/07\/cropped-Logo-trasparente-1.png","contentUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2021\/07\/cropped-Logo-trasparente-1.png","width":775,"height":367,"caption":"Colli Vai Bo"},"image":{"@id":"https:\/\/collivaibo.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/collivaibo.it\/#\/schema\/person\/850b4c503bc845b7601f6b66d8fc754c","name":"Madl","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g","caption":"Madl"},"sameAs":["https:\/\/madl-image.it\/"],"url":"https:\/\/collivaibo.it\/en\/author\/wp-madl\/"}]}},"_links":{"self":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts\/7596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/users\/218"}],"replies":[{"embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/comments?post=7596"}],"version-history":[{"count":2,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts\/7596\/revisions"}],"predecessor-version":[{"id":7598,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts\/7596\/revisions\/7598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/media\/9495"}],"wp:attachment":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/media?parent=7596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/categories?post=7596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/tags?post=7596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}