

{"id":8485,"date":"2025-08-11T10:07:35","date_gmt":"2025-08-11T09:07:35","guid":{"rendered":"https:\/\/collivaibo.it\/?p=8485"},"modified":"2025-08-11T10:07:35","modified_gmt":"2025-08-11T09:07:35","slug":"lugana-2023-bronze-medal-iwsc-2","status":"publish","type":"post","link":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/","title":{"rendered":"LUGANA 2023 &#8211; BRONZE MEDAL IWSC"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8485\" class=\"elementor elementor-8485 elementor-8483\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f49906 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f49906\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-933a306\" data-id=\"933a306\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dbab60 elementor-widget elementor-widget-image\" data-id=\"3dbab60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90.png\" class=\"attachment-large size-large wp-image-8452\" alt=\"\" srcset=\"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90.png 800w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-300x300.png 300w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-150x150.png 150w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-768x768.png 768w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-630x630.png 630w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-600x600.png 600w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-100x100.png 100w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-50x50.png 50w, https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90-460x460.png 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed40f97 elementor-widget elementor-widget-heading\" data-id=\"ed40f97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">FALSTAFF GARDASEE TROPHY 2022<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c22d97 elementor-widget elementor-widget-text-editor\" data-id=\"2c22d97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Vino vincitore: Lugana 24<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FALSTAFF GARDASEE TROPHY 2022 Vino vincitore: Lugana 24<\/p>\n","protected":false},"author":218,"featured_media":9550,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LUGANA 2023 - BRONZE MEDAL IWSC - Colli Vai Bo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LUGANA 2023 - BRONZE MEDAL IWSC - Colli Vai Bo\" \/>\n<meta property=\"og:description\" content=\"FALSTAFF GARDASEE TROPHY 2022 Vino vincitore: Lugana 24\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Colli Vai Bo\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-11T09:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Madl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Madl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/\"},\"author\":{\"name\":\"Madl\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/person\\\/850b4c503bc845b7601f6b66d8fc754c\"},\"headline\":\"LUGANA 2023 &#8211; BRONZE MEDAL IWSC\",\"datePublished\":\"2025-08-11T09:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/10.png\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/\",\"name\":\"LUGANA 2023 - BRONZE MEDAL IWSC - Colli Vai Bo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/10.png\",\"datePublished\":\"2025-08-11T09:07:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/10.png\",\"contentUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/10.png\",\"width\":2060,\"height\":1481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/lugana-2023-bronze-medal-iwsc-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LUGANA 2023 &#8211; BRONZE MEDAL IWSC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"name\":\"Colli Vai Bo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collivaibo.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\",\"name\":\"Colli Vai Bo\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-Logo-trasparente-1.png\",\"contentUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-Logo-trasparente-1.png\",\"width\":775,\"height\":367,\"caption\":\"Colli Vai Bo\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/person\\\/850b4c503bc845b7601f6b66d8fc754c\",\"name\":\"Madl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g\",\"caption\":\"Madl\"},\"sameAs\":[\"https:\\\/\\\/madl-image.it\\\/\"],\"url\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/author\\\/wp-madl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LUGANA 2023 - BRONZE MEDAL IWSC - Colli Vai Bo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/","og_locale":"en_US","og_type":"article","og_title":"LUGANA 2023 - BRONZE MEDAL IWSC - Colli Vai Bo","og_description":"FALSTAFF GARDASEE TROPHY 2022 Vino vincitore: Lugana 24","og_url":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/","og_site_name":"Colli Vai Bo","article_published_time":"2025-08-11T09:07:35+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/07\/SILVER_2025_90.png","type":"image\/png"}],"author":"Madl","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Madl","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#article","isPartOf":{"@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/"},"author":{"name":"Madl","@id":"https:\/\/collivaibo.it\/#\/schema\/person\/850b4c503bc845b7601f6b66d8fc754c"},"headline":"LUGANA 2023 &#8211; BRONZE MEDAL IWSC","datePublished":"2025-08-11T09:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/"},"wordCount":11,"publisher":{"@id":"https:\/\/collivaibo.it\/#organization"},"image":{"@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#primaryimage"},"thumbnailUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/08\/10.png","articleSection":["Non categorizzato"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/","url":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/","name":"LUGANA 2023 - BRONZE MEDAL IWSC - Colli Vai Bo","isPartOf":{"@id":"https:\/\/collivaibo.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#primaryimage"},"image":{"@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#primaryimage"},"thumbnailUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/08\/10.png","datePublished":"2025-08-11T09:07:35+00:00","breadcrumb":{"@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#primaryimage","url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/08\/10.png","contentUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2025\/08\/10.png","width":2060,"height":1481},{"@type":"BreadcrumbList","@id":"https:\/\/collivaibo.it\/en\/lugana-2023-bronze-medal-iwsc-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/collivaibo.it\/en\/"},{"@type":"ListItem","position":2,"name":"LUGANA 2023 &#8211; BRONZE MEDAL IWSC"}]},{"@type":"WebSite","@id":"https:\/\/collivaibo.it\/#website","url":"https:\/\/collivaibo.it\/","name":"Colli Vai Bo","description":"","publisher":{"@id":"https:\/\/collivaibo.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collivaibo.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/collivaibo.it\/#organization","name":"Colli Vai Bo","url":"https:\/\/collivaibo.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collivaibo.it\/#\/schema\/logo\/image\/","url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2021\/07\/cropped-Logo-trasparente-1.png","contentUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2021\/07\/cropped-Logo-trasparente-1.png","width":775,"height":367,"caption":"Colli Vai Bo"},"image":{"@id":"https:\/\/collivaibo.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/collivaibo.it\/#\/schema\/person\/850b4c503bc845b7601f6b66d8fc754c","name":"Madl","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33bed6bb9ea16699695c31ecb5158507693e3c1fda1a22fea40ddd491158a3ce?s=96&d=mm&r=g","caption":"Madl"},"sameAs":["https:\/\/madl-image.it\/"],"url":"https:\/\/collivaibo.it\/en\/author\/wp-madl\/"}]}},"_links":{"self":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts\/8485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/users\/218"}],"replies":[{"embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/comments?post=8485"}],"version-history":[{"count":1,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts\/8485\/revisions"}],"predecessor-version":[{"id":8487,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/posts\/8485\/revisions\/8487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/media\/9550"}],"wp:attachment":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/media?parent=8485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/categories?post=8485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/tags?post=8485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}