{"id":81,"count":2,"description":"","link":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/","name":"Rosati","slug":"rosati-en","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rosati Archivi - Colli Vai Bo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rosati Archivi - Colli Vai Bo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Colli Vai Bo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/categoria-prodotto\\\/rosati-en\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/categoria-prodotto\\\/rosati-en\\\/\",\"name\":\"Rosati Archivi - Colli Vai Bo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/categoria-prodotto\\\/rosati-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/categoria-prodotto\\\/rosati-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/collivaibo.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rosati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#website\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"name\":\"Colli Vai Bo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collivaibo.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#organization\",\"name\":\"Colli Vai Bo\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-Logo-trasparente-1.png\",\"contentUrl\":\"https:\\\/\\\/collivaibo.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cropped-Logo-trasparente-1.png\",\"width\":775,\"height\":367,\"caption\":\"Colli Vai Bo\"},\"image\":{\"@id\":\"https:\\\/\\\/collivaibo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rosati Archivi - Colli Vai Bo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/","og_locale":"en_US","og_type":"article","og_title":"Rosati Archivi - Colli Vai Bo","og_url":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/","og_site_name":"Colli Vai Bo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/","url":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/","name":"Rosati Archivi - Colli Vai Bo","isPartOf":{"@id":"https:\/\/collivaibo.it\/#website"},"breadcrumb":{"@id":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/collivaibo.it\/en\/categoria-prodotto\/rosati-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/collivaibo.it\/en\/"},{"@type":"ListItem","position":2,"name":"Rosati"}]},{"@type":"WebSite","@id":"https:\/\/collivaibo.it\/#website","url":"https:\/\/collivaibo.it\/","name":"Colli Vai Bo","description":"","publisher":{"@id":"https:\/\/collivaibo.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collivaibo.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/collivaibo.it\/#organization","name":"Colli Vai Bo","url":"https:\/\/collivaibo.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collivaibo.it\/#\/schema\/logo\/image\/","url":"https:\/\/collivaibo.it\/wp-content\/uploads\/2021\/07\/cropped-Logo-trasparente-1.png","contentUrl":"https:\/\/collivaibo.it\/wp-content\/uploads\/2021\/07\/cropped-Logo-trasparente-1.png","width":775,"height":367,"caption":"Colli Vai Bo"},"image":{"@id":"https:\/\/collivaibo.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/product_cat\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/collivaibo.it\/en\/wp-json\/wp\/v2\/product?product_cat=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}